{"id":41243,"date":"2024-06-02T17:29:23","date_gmt":"2024-06-02T17:29:23","guid":{"rendered":"https:\/\/topsecretsicily.com\/sin-categorizar\/que-ver-en-calascibetta-el-pueblo-medieval\/"},"modified":"2025-05-09T20:18:54","modified_gmt":"2025-05-09T20:18:54","slug":"que-ver-en-calascibetta-el-pueblo-medieval","status":"publish","type":"post","link":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/","title":{"rendered":"Qu\u00e9 ver en Calascibetta &#8211; El pueblo medieval"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;41243&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;7&quot;,&quot;greet&quot;:&quot;Vote article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Qu\u00e9 ver en Calascibetta - El pueblo medieval&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Vote article<\/span>\n    <\/div>\n    <\/div>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Introduccion\" >Introducci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Que_ver_en_Calascibetta\" >Qu\u00e9 ver en Calascibetta<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#El_centro_historico\" >El centro hist\u00f3rico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Las_cuevas\" >Las cuevas<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Donde_comer_en_Calascibetta\" >D\u00f3nde comer en Calascibetta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Mapa_interactivo_de_Calascibetta\" >Mapa interactivo de Calascibetta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Actividades_mas_populares_para_turistas_en_Sicilia\" >Actividades m\u00e1s populares para turistas en Sicilia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Que_ver_en_los_alrededores\" >Qu\u00e9 ver en los alrededores<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#Platos_tipicos_en_Enna_y_alrededores\" >Platos t\u00edpicos en Enna y alrededores<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Introduccion\"><\/span>Introducci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>En este art\u00edculo descubrir\u00e1s qu\u00e9 ver en Calascibetta. Es un pueblo medieval poco conocido, pero realmente muy bonito y con algunos hallazgos arqueol\u00f3gicos notables<\/strong>. El nombre tiene origen \u00e1rabe, pero fueron los normandos quienes sancionaron el nacimiento del pueblo hacia el siglo XI. El pueblo tambi\u00e9n es visible desde <a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-enna-el-pueblo-siciliano-con-niebla\/\" target=\"_blank\" rel=\"noreferrer noopener\">Enna<\/a>, desde donde tienes una vista fant\u00e1stica de \u00e9l y de las colinas circundantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_in_Sicily-1024x678.jpg\" alt=\"Qu\u00e9 ver en Calascibetta\" class=\"wp-image-6581\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_in_Sicily-1024x678.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_in_Sicily-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_in_Sicily-768x509.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_in_Sicily.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Calascibetta_in_Sicily.jpg\">Yulka-lucia<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\">CC BY-SA 4.0<\/a>, v\u00eda Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_Enna_Sicily_Italy_-_panoramio-1024x577.jpg\" alt=\"Calascibetta\" class=\"wp-image-6584\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_Enna_Sicily_Italy_-_panoramio-1024x577.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_Enna_Sicily_Italy_-_panoramio-300x169.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_Enna_Sicily_Italy_-_panoramio-768x433.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_Enna_Sicily_Italy_-_panoramio.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Calascibetta,_Enna,_Sicily,_Italy_-_panoramio.jpg\">trolvag<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a>, v\u00eda Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Conveto_dei_frati_cappuccini_Calascibetta_EN_Sicily_Italy_-_panoramio-1024x577.jpg\" alt=\"Convento de los Frailes Capuchinos, Calascibetta\" class=\"wp-image-6585\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Conveto_dei_frati_cappuccini_Calascibetta_EN_Sicily_Italy_-_panoramio-1024x577.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Conveto_dei_frati_cappuccini_Calascibetta_EN_Sicily_Italy_-_panoramio-300x169.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Conveto_dei_frati_cappuccini_Calascibetta_EN_Sicily_Italy_-_panoramio-768x433.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Conveto_dei_frati_cappuccini_Calascibetta_EN_Sicily_Italy_-_panoramio.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Convento de los Frailes Capuchinos &#8211; <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Conveto_dei_frati_cappuccini,_Calascibetta_EN,_Sicily,_Italy_-_panoramio.jpg\">trolvag<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a>, v\u00eda Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Madonna_del_Carmine_Calascibetta_EN_Sicily_Italy_-_panoramio-1024x576.jpg\" alt=\"Iglesia del Carmelo, Calascibetta\" class=\"wp-image-6588\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Madonna_del_Carmine_Calascibetta_EN_Sicily_Italy_-_panoramio-1024x576.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Madonna_del_Carmine_Calascibetta_EN_Sicily_Italy_-_panoramio-300x169.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Madonna_del_Carmine_Calascibetta_EN_Sicily_Italy_-_panoramio-768x432.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Madonna_del_Carmine_Calascibetta_EN_Sicily_Italy_-_panoramio.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Iglesia carmelita- <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Madonna_del_Carmine,_Calascibetta_EN,_Sicily,_Italy_-_panoramio.jpg\">trolvag<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a>, v\u00eda Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_ver_en_Calascibetta\"><\/span>Qu\u00e9 ver en Calascibetta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"El_centro_historico\"><\/span>El centro hist\u00f3rico<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Volviendo <strong>a la historia del pueblo de Calascibetta, Roger el Normando construy\u00f3 aqu\u00ed un castillo (del que s\u00f3lo queda una torre) que rode\u00f3 de murallas, convirti\u00e9ndolo en la base de operaciones para atacar y derrotar a la ciudad de Enna<\/strong>. Despu\u00e9s de muchos a\u00f1os, la plaza panor\u00e1mica dominada por la torre y la iglesia adyacente (tambi\u00e9n mandada construir por Roger el Normando) ha sido reabierta y ya puede visitarse.<\/p>\n\n\n\n<p><strong>Otro lugar que te recomiendo ver es el barrio jud\u00edo, cuyo origen se remonta al siglo XIV.<\/strong> Los jud\u00edos viv\u00edan aqu\u00ed lejos de los cristianos, pero eran tolerados y se dedicaban al comercio, la usura y la artesan\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"879\" height=\"1023\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_-_Torre_Normanna_XI_sec_e_Chiesa_abbandonata_-_panoramio.jpg\" alt=\"\" class=\"wp-image-6590\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_-_Torre_Normanna_XI_sec_e_Chiesa_abbandonata_-_panoramio.jpg 879w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_-_Torre_Normanna_XI_sec_e_Chiesa_abbandonata_-_panoramio-258x300.jpg 258w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Calascibetta_-_Torre_Normanna_XI_sec_e_Chiesa_abbandonata_-_panoramio-768x894.jpg 768w\" sizes=\"auto, (max-width: 879px) 100vw, 879px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Calascibetta_-_Torre_Normanna_XI_sec_e_Chiesa_abbandonata_-_panoramio.jpg\">giomodica<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by\/3.0\">CC BY 3.0<\/a>, v\u00eda Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"813\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/uytuty.png\" alt=\"Barrio Jud\u00edo, Calascibetta\" class=\"wp-image-2317\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/uytuty.png 1001w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/uytuty-300x244.png 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/uytuty-768x624.png 768w\" sizes=\"auto, (max-width: 1001px) 100vw, 1001px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las_cuevas\"><\/span>Las cuevas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En la <strong>V\u00eda Carcere tambi\u00e9n hay antiguas cuevas excavadas en la<\/strong> roca, probablemente de origen bizantino. Sin embargo, esto es s\u00f3lo un anticipo de lo que te espera no muy lejos del pueblo, una aldea entera construida en la roca, la <a href=\"https:\/\/topsecretsicily.com\/calascibetta-villaggio-bizantino-scavato-nella-roccia\/\" target=\"_blank\" rel=\"noreferrer noopener\">aldea<\/a><a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/el-pueblo-bizantino-canalotto-excavado-en-la-roca\/\" target=\"_blank\" rel=\"noreferrer noopener\">bizantina<\/a><a href=\"https:\/\/topsecretsicily.com\/calascibetta-villaggio-bizantino-scavato-nella-roccia\/\" target=\"_blank\" rel=\"noreferrer noopener\"> de Canalotto<\/a>.<\/p>\n\n\n\n<p>Por \u00faltimo, en Calascibetta puedes visitar varias iglesias, que figuran en el mapa interactivo que he preparado a continuaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1005\" height=\"822\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/tyrt.png\" alt=\"Necr\u00f3polis, calascibetta, calle de la prisi\u00f3n\" class=\"wp-image-2316\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/tyrt.png 1005w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/tyrt-300x245.png 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/tyrt-768x628.png 768w\" sizes=\"auto, (max-width: 1005px) 100vw, 1005px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dove-mangiare-a-calascibetta\"><span class=\"ez-toc-section\" id=\"Donde_comer_en_Calascibetta\"><\/span>D\u00f3nde comer en Calascibetta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Por \u00faltimo, en la plaza Umberto I y sus alrededores encontrar\u00e1s bares, pasteler\u00edas y restaurantes, donde podr\u00e1s comer productos y platos t\u00edpicos. En el restaurante La Lanterna, podr\u00e1s disfrutar de excelentes entremeses y platos de carne y pescado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mappa-interattiva-di-calascibetta\"><span class=\"ez-toc-section\" id=\"Mapa_interactivo_de_Calascibetta\"><\/span>Mapa interactivo de Calascibetta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para situarte una vez en la zona, haz clic en el s\u00edmbolo de ampliaci\u00f3n situado en la parte superior derecha del mapa<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/u\/0\/embed?mid=1h8KBYlNgo6peVZ-gV_Fq8PTTBkhbTVAp\" width=\"999\" height=\"480\"><\/iframe><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Actividades_mas_populares_para_turistas_en_Sicilia\"><\/span>Actividades m\u00e1s populares para turistas en Sicilia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div data-gyg-widget=\"auto\" data-gyg-partner-id=\"2MY8JNV\" data-gyg-cmp=\"Calascibetta\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cosa-vedere-nei-dintorni\"><span class=\"ez-toc-section\" id=\"Que_ver_en_los_alrededores\"><\/span>Qu\u00e9 ver en los alrededores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Calascibetta forma parte de la provincia de Enna. \u00c9stos son los <a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/\">lugares m\u00e1s bellos<\/a><a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/\" target=\"_blank\" rel=\"noreferrer noopener\"> <\/a><a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/\">que visitar en los alrededores de Enna<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-piatti-tipici-di-enna-e-dintorni\"><span class=\"ez-toc-section\" id=\"Platos_tipicos_en_Enna_y_alrededores\"><\/span>Platos t\u00edpicos en Enna y alrededores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Calascibetta est\u00e1 situada, como ya se ha dicho, en la provincia de Enna. \u00bfQuieres probar platos t\u00edpicos de la zona de Enna? Aqu\u00ed escrib\u00ed un art\u00edculo sobre <a href=\"https:\/\/topsecretsicily.com\/es\/alimentacion\/descubre-que-comer-en-enna-y-sus-alrededores\/\" target=\"_blank\" rel=\"noreferrer noopener\">qu\u00e9 comer en Enna<\/a> y sus alrededores.<\/p>\n\n\n\n<p>Aqu\u00ed encontrar\u00e1s <a href=\"https:\/\/topsecretsicily.com\/es\/alimentacion\/descubre-los-platos-y-productos-tipicos-de-sicilia\/\" target=\"_blank\" rel=\"noopener\" title=\"Descubre los platos y productos t\u00edpicos de Sicilia\">platos t\u00edpicos sicilianos <\/a>en general.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":41323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[267],"tags":[],"class_list":["post-41243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia-de-enna"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Introducci\u00f3n En este art\u00edculo descubrir\u00e1s qu\u00e9 ver en Calascibetta. Es un pueblo medieval poco conocido, pero realmente muy bonito y con algunos hallazgos arqueol\u00f3gicos notables. El nombre tiene origen \u00e1rabe, pero fueron los normandos quienes sancionaron el nacimiento del pueblo hacia el siglo XI. El pueblo tambi\u00e9n es visible desde Enna, desde donde tienes una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dario Lo Turco\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#blogposting\",\"name\":\"Qu\\u00e9 ver en Calascibetta \\u2013 El pueblo medieval\",\"headline\":\"Qu\\u00e9 ver en Calascibetta &#8211; El pueblo medieval\",\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/author\\\/erf87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Calascibetta_in_Sicily.webp\",\"width\":1280,\"height\":848},\"datePublished\":\"2024-06-02T17:29:23+00:00\",\"dateModified\":\"2025-05-09T20:18:54+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#webpage\"},\"articleSection\":\"Provincia de Enna, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/#listItem\",\"name\":\"Provincia de Enna\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/#listItem\",\"position\":2,\"name\":\"Provincia de Enna\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#listItem\",\"name\":\"Qu\\u00e9 ver en Calascibetta &#8211; El pueblo medieval\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#listItem\",\"position\":3,\"name\":\"Qu\\u00e9 ver en Calascibetta &#8211; El pueblo medieval\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/#listItem\",\"name\":\"Provincia de Enna\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#organization\",\"name\":\"Top Secret Sicily\",\"description\":\"Gu\\u00eda interactiva de Sicilia\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/\",\"telephone\":\"+49176973190086\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-prickly-pear-50.png\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#organizationLogo\",\"width\":50,\"height\":50},\"image\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/topsecretsicily\",\"https:\\\/\\\/www.instagram.com\\\/topsecretsicily\",\"https:\\\/\\\/www.tiktok.com\\\/@topsecretsicily.com\",\"https:\\\/\\\/www.youtube.com\\\/@Topsecretsicily\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/author\\\/erf87\\\/#author\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/author\\\/erf87\\\/\",\"name\":\"Dario Lo Turco\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dario Lo Turco\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#webpage\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/\",\"name\":\"Qu\\u00e9 ver en Calascibetta \\u2013 El pueblo medieval\",\"description\":\"Introducci\\u00f3n En este art\\u00edculo descubrir\\u00e1s qu\\u00e9 ver en Calascibetta. Es un pueblo medieval poco conocido, pero realmente muy bonito y con algunos hallazgos arqueol\\u00f3gicos notables. El nombre tiene origen \\u00e1rabe, pero fueron los normandos quienes sancionaron el nacimiento del pueblo hacia el siglo XI. El pueblo tambi\\u00e9n es visible desde Enna, desde donde tienes una\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/author\\\/erf87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/author\\\/erf87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Calascibetta_in_Sicily.webp\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#mainImage\",\"width\":1280,\"height\":848},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/provincia-de-enna\\\/que-ver-en-calascibetta-el-pueblo-medieval\\\/#mainImage\"},\"datePublished\":\"2024-06-02T17:29:23+00:00\",\"dateModified\":\"2025-05-09T20:18:54+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/\",\"name\":\"Top Secret Sicily\",\"description\":\"Gu\\u00eda interactiva de Sicilia\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Qu\u00e9 ver en Calascibetta \u2013 El pueblo medieval","description":"Introducci\u00f3n En este art\u00edculo descubrir\u00e1s qu\u00e9 ver en Calascibetta. Es un pueblo medieval poco conocido, pero realmente muy bonito y con algunos hallazgos arqueol\u00f3gicos notables. El nombre tiene origen \u00e1rabe, pero fueron los normandos quienes sancionaron el nacimiento del pueblo hacia el siglo XI. El pueblo tambi\u00e9n es visible desde Enna, desde donde tienes una","canonical_url":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#blogposting","name":"Qu\u00e9 ver en Calascibetta \u2013 El pueblo medieval","headline":"Qu\u00e9 ver en Calascibetta &#8211; El pueblo medieval","author":{"@id":"https:\/\/topsecretsicily.com\/es\/author\/erf87\/#author"},"publisher":{"@id":"https:\/\/topsecretsicily.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/11\/Calascibetta_in_Sicily.webp","width":1280,"height":848},"datePublished":"2024-06-02T17:29:23+00:00","dateModified":"2025-05-09T20:18:54+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#webpage"},"isPartOf":{"@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#webpage"},"articleSection":"Provincia de Enna, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/topsecretsicily.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/#listItem","name":"Provincia de Enna"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/#listItem","position":2,"name":"Provincia de Enna","item":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#listItem","name":"Qu\u00e9 ver en Calascibetta &#8211; El pueblo medieval"},"previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#listItem","position":3,"name":"Qu\u00e9 ver en Calascibetta &#8211; El pueblo medieval","previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/#listItem","name":"Provincia de Enna"}}]},{"@type":"Organization","@id":"https:\/\/topsecretsicily.com\/es\/#organization","name":"Top Secret Sicily","description":"Gu\u00eda interactiva de Sicilia","url":"https:\/\/topsecretsicily.com\/es\/","telephone":"+49176973190086","logo":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/03\/cropped-prickly-pear-50.png","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#organizationLogo","width":50,"height":50},"image":{"@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/topsecretsicily","https:\/\/www.instagram.com\/topsecretsicily","https:\/\/www.tiktok.com\/@topsecretsicily.com","https:\/\/www.youtube.com\/@Topsecretsicily"]},{"@type":"Person","@id":"https:\/\/topsecretsicily.com\/es\/author\/erf87\/#author","url":"https:\/\/topsecretsicily.com\/es\/author\/erf87\/","name":"Dario Lo Turco","image":{"@type":"ImageObject","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dario Lo Turco"}},{"@type":"WebPage","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#webpage","url":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/","name":"Qu\u00e9 ver en Calascibetta \u2013 El pueblo medieval","description":"Introducci\u00f3n En este art\u00edculo descubrir\u00e1s qu\u00e9 ver en Calascibetta. Es un pueblo medieval poco conocido, pero realmente muy bonito y con algunos hallazgos arqueol\u00f3gicos notables. El nombre tiene origen \u00e1rabe, pero fueron los normandos quienes sancionaron el nacimiento del pueblo hacia el siglo XI. El pueblo tambi\u00e9n es visible desde Enna, desde donde tienes una","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/topsecretsicily.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#breadcrumblist"},"author":{"@id":"https:\/\/topsecretsicily.com\/es\/author\/erf87\/#author"},"creator":{"@id":"https:\/\/topsecretsicily.com\/es\/author\/erf87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/11\/Calascibetta_in_Sicily.webp","@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#mainImage","width":1280,"height":848},"primaryImageOfPage":{"@id":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/#mainImage"},"datePublished":"2024-06-02T17:29:23+00:00","dateModified":"2025-05-09T20:18:54+00:00"},{"@type":"WebSite","@id":"https:\/\/topsecretsicily.com\/es\/#website","url":"https:\/\/topsecretsicily.com\/es\/","name":"Top Secret Sicily","description":"Gu\u00eda interactiva de Sicilia","inLanguage":"es-ES","publisher":{"@id":"https:\/\/topsecretsicily.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"41243","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Cosa vedere a Calascibetta","score":78,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2024-06-02 17:29:29","updated":"2025-02-09 21:21:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/\" title=\"Provincia de Enna\">Provincia de Enna<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQu\u00e9 ver en Calascibetta \u2013 El pueblo medieval\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/topsecretsicily.com\/es\/"},{"label":"Provincia de Enna","link":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/"},{"label":"Qu\u00e9 ver en Calascibetta &#8211; El pueblo medieval","link":"https:\/\/topsecretsicily.com\/es\/provincia-de-enna\/que-ver-en-calascibetta-el-pueblo-medieval\/"}],"modified_by":null,"_links":{"self":[{"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/posts\/41243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/comments?post=41243"}],"version-history":[{"count":5,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/posts\/41243\/revisions"}],"predecessor-version":[{"id":51398,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/posts\/41243\/revisions\/51398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/media\/41323"}],"wp:attachment":[{"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/media?parent=41243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/categories?post=41243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/topsecretsicily.com\/es\/wp-json\/wp\/v2\/tags?post=41243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}