{"id":21721,"date":"2021-11-01T11:33:14","date_gmt":"2021-11-01T11:33:14","guid":{"rendered":"https:\/\/topsecretsicily.com\/non-classifiee\/brucoli-chateau-eglise-rupestre-et-plage\/"},"modified":"2025-02-10T18:45:16","modified_gmt":"2025-02-10T18:45:16","slug":"brucoli-chateau-eglise-rupestre-et-plage","status":"publish","type":"post","link":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/","title":{"rendered":"Que voir \u00e0 Brucoli &#8211; ch\u00e2teau, \u00e9glise rupestre et plage"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;21721&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;7&quot;,&quot;greet&quot;:&quot;\u00c9valuer l\\u0026#039;article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Que voir \u00e0 Brucoli - ch\u00e2teau, \u00e9glise rupestre et plage&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">\u00c9valuer l&#039;article<\/span>\n    <\/div>\n    <\/div>\n\n<p>Brucoli est un petit village c\u00f4tier de la province de Syracuse. <strong>Si vous avez envie d&rsquo;admirer le ch\u00e2teau qui surplombe la mer, de respirer l&rsquo;air frais ou de faire quelques excursions en bateau dans la r\u00e9gion, une visite<\/strong> s&rsquo;impose. Il est juste de souligner que le ch\u00e2teau aragonais est malheureusement actuellement ferm\u00e9 pour restauration. Cependant, m\u00eame de l&rsquo;ext\u00e9rieur, il est tr\u00e8s beau, et si vous vous promenez autour, vous pouvez profiter de vues magnifiques, avec la mer et l&rsquo;<a href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/visitez-letna-et-montez-directement-au-sommet-du-volcan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Etna<\/a> (si le temps le permet) en arri\u00e8re-plan, qui vu d&rsquo;ici semble surgir de la mer.<\/p>\n\n<p><strong>A visiter \u00e9galement la baie, une crique entre les rochers, o\u00f9 se trouvent encore des grottes utilis\u00e9es depuis la pr\u00e9histoire. Dans le petit port, le dimanche matin, vous pouvez acheter du poisson fra\u00eechement p\u00each\u00e9 et m\u00eame louer un bateau pour quelques heures.<\/strong>.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_89-1.jpg\" alt=\"Brucoli\" class=\"wp-image-7132\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_89-1.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_89-1-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_89-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_(89).jpg\">gnuckx<\/a> ,<a href=\"https:\/\/creativecommons.org\/licenses\/by\/3.0\"> CC BY 3.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_5017949937-1024x680.jpg\" alt=\"Ch&#xE2;teau de Brucoli\" class=\"wp-image-7133\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_5017949937-1024x680.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_5017949937-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_5017949937-768x510.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/1280px-Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_5017949937.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Brucoli_Sicilia_Italy_-_Creative_Commons_by_gnuckx_(5017949937).jpg\">gnuckx<\/a> ,<a href=\"https:\/\/creativecommons.org\/licenses\/by\/2.0\"> CC BY 2.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Castello_di_Brucoli_003.jpg\" alt=\"Ch&#xE2;teau de Brucoli\" class=\"wp-image-7134\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Castello_di_Brucoli_003.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Castello_di_Brucoli_003-300x148.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Castello_di_Brucoli_003-768x379.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Castello_di_Brucoli_003.JPG\">Mariobri93<\/a> , <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\">CC BY-SA 4.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"735\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Canale_Brucoli-1024x735.jpg\" alt=\"Brucoli\" class=\"wp-image-7135\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Canale_Brucoli-1024x735.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Canale_Brucoli-300x215.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Canale_Brucoli-768x551.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Canale_Brucoli.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Canale_Brucoli.jpg\">Giada57 sur Wikipedia italien<\/a> , <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_38-1.jpg\" alt=\"Brucoli\" class=\"wp-image-7136\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_38-1.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_38-1-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_38-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Brucoli_Syracuse_Sicily_Italy_-_Creative_Commons_by_gnuckx_-_panoramio_(38).jpg\">gnuckx<\/a> ,<a href=\"https:\/\/creativecommons.org\/licenses\/by\/3.0\"> CC BY 3.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Le_sanctuaire\" >Le sanctuaire<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Astuce_Top_Secret_%E2%80%93_Brucoli_Beach\" >Astuce Top Secret &#8211; Brucoli Beach<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Ou_manger_a_Brucoli\" >O\u00f9 manger \u00e0 Brucoli<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Carte_interactive_Brucoli_et_environs_%E2%80%93_Points_dinteret_en_violet\" >Carte interactive Brucoli et environs &#8211; Points d&rsquo;int\u00e9r\u00eat en violet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Plats_typiques_de_Syracuse_et_ses_environs\" >Plats typiques de Syracuse et ses environs<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#Activites_les_plus_populaires_pour_les_touristes_en_Sicile\" >Activit\u00e9s les plus populaires pour les touristes en Sicile<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Le_sanctuaire\"><\/span>Le sanctuaire<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Tr\u00e8s sympa aussi <strong>le Sanctuaire d&rsquo;Adona\u00ef, surplombant la mer, \u00e0 quelques kilom\u00e8tres du centre de Brucoli. Le monast\u00e8re a \u00e9t\u00e9 cr\u00e9\u00e9 au 16\u00e8me si\u00e8cle<\/strong>, mais le lieu de culte r\u00e9el est situ\u00e9 dans une grotte, o\u00f9 se trouve la peinture de la Vierge datant du IIIe si\u00e8cle apr\u00e8s J.-C. La peinture a \u00e9t\u00e9 cr\u00e9\u00e9e par un chr\u00e9tien qui a \u00e9chapp\u00e9 \u00e0 la pers\u00e9cution romaine et est devenu plus tard un lieu sacr\u00e9. L&rsquo;\u00e9glise apr\u00e8s l&rsquo;\u00e9dit de Constantin fut cependant abandonn\u00e9e et on n&rsquo;en entendit plus parler. Une th\u00e9orie veut qu&rsquo;au moment de l&rsquo;invasion arabe, il \u00e9tait cach\u00e9 pour ne pas \u00eatre d\u00e9truit. <\/p>\n\n<p>Le sanctuaire est ouvert, sauf changement d&rsquo;horaire, les mardis et samedis de 9h00 \u00e0 11h30 et les dimanches de 15h00 \u00e0 18h30.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o-1024x768.jpg\" alt=\"Sanctuaire d'Adona&#xEF;, Brucoli\" class=\"wp-image-7130\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o-1024x768.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o-768x576.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o-1536x1152.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/3196668830_9823d78d92_o.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">sanctuaire<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3-1024x680.jpg\" alt=\"Sanctuaire d'Adona&#xEF;, Brucoli\" class=\"wp-image-7128\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3-1024x680.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3-768x510.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3-1536x1020.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/DA-INSERIRE-3.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16-1024x680.jpg\" alt=\"Sanctuaire d'Adona&#xEF;, Brucoli\" class=\"wp-image-7131\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16-1024x680.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16-300x199.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16-768x510.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16-1536x1020.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/aa-16.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-consiglio-top-secret-spiaggia-brucoli\"><span class=\"ez-toc-section\" id=\"Astuce_Top_Secret_%E2%80%93_Brucoli_Beach\"><\/span>Astuce Top Secret &#8211; Brucoli Beach <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>A proximit\u00e9 se trouve <strong>une plage un peu difficile \u00e0 atteindre, mais avec une eau vraiment cristalline et entour\u00e9e par la nature<\/strong> . Pour y acc\u00e9der, il faut emprunter un chemin de terre puis continuer \u00e0 pied quelques minutes en direction de Brucoli. Arrivez en voiture <a rel=\"noreferrer noopener\" href=\"https:\/\/www.google.com\/maps\/place\/Parking\/@37.289258,15.1995923,16z\/data=!4m13!1m7!3m6!1s0x1313dce437b1a943:0x930d3835341111d6!2s96011+Brucoli,+Syrakus,+Italien!3b1!8m2!3d37.2819068!4d15.1883475!3m4!1s0x1313dd2443bd6777:0x2d62a1c5cdc4f9b3!8m2!3d37.2930228!4d15.2036646\" target=\"_blank\">jusqu&rsquo;ici<\/a> puis continuez \u00e0 pied en direction de Punta Tonnara. De l\u00e0, vous pourrez \u00e9galement admirer l&rsquo;Etna au loin, si le temps le permet bien s\u00fbr.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1070\" height=\"708\" src=\"https:\/\/i2.wp.com\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/rere.png?fit=800%2C530\" alt=\"Pointe Tonnara - Brucoli\" class=\"wp-image-2535\" style=\"width:880px;height:auto\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/rere.png 1070w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/rere-300x199.png 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/rere-1024x678.png 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/05\/rere-768x508.png 768w\" sizes=\"auto, (max-width: 1070px) 100vw, 1070px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-dove-mangiare-a-brucoli\"><span class=\"ez-toc-section\" id=\"Ou_manger_a_Brucoli\"><\/span>O\u00f9 manger \u00e0 Brucoli<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>A Brucoli nous vous recommandons la Trattoria i Rizzari, un endroit tr\u00e8s agr\u00e9able \u00e0 2 pas de la mer, avec une terrasse en bois sur les rochers. C&rsquo;\u00e9tait autrefois une maison de p\u00eacheur et cela rend l&rsquo;atmosph\u00e8re encore plus charmante. Les plats sont \u00e0 base de poisson.<\/p>\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3174.480531702222!2d15.1880364!3d37.2837436!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1313dce390689ac9%3A0xb96671055e8e41c3!2sTrattoria%20I%20Rizzari!5e0!3m2!1sde!2sde!4v1589263970874!5m2!1sde!2sde\" width=\"999\" height=\"450\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-mappa-interattiva-brucoli-e-dintorni-punti-d-interesse-in-viola\"><span class=\"ez-toc-section\" id=\"Carte_interactive_Brucoli_et_environs_%E2%80%93_Points_dinteret_en_violet\"><\/span>Carte interactive Brucoli et environs &#8211; Points d&rsquo;int\u00e9r\u00eat en violet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Pour vous situer une fois dans la zone, cliquez sur le symbole agrandir en haut \u00e0 droite de la carte.<\/p>\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/u\/0\/embed?mid=1Rb_6OiQdOkDMvHbkUaqjeR0QA-zOk3aL\" width=\"999\" height=\"480\"><\/iframe><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-piatti-tipici-di-siracusa-e-dintorni\"><span class=\"ez-toc-section\" id=\"Plats_typiques_de_Syracuse_et_ses_environs\"><\/span>Plats typiques de Syracuse et ses environs<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Brucoli est situ\u00e9 dans la province de Syracuse. Voulez-vous essayer les plats typiques de cette r\u00e9gion? Ici vous pouvez trouver un article sur <a href=\"https:\/\/topsecretsicily.com\/fr\/nourriture\/que-manger-a-syracuse-et-ses-environs\/\" target=\"_blank\" rel=\"noreferrer noopener\">ce qu&rsquo;il faut manger \u00e0 Syracuse et ses environs<\/a> .<\/p>\n\n<p>Ici, \u00e0 la place, vous trouvez le<a href=\"https:\/\/topsecretsicily.com\/fr\/nourriture\/plats-et-produits-typiques-siciliens\/\" target=\"_blank\" rel=\"noreferrer noopener\"> plats et produits typiques siciliens<\/a> en g\u00e9n\u00e9ral.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Activites_les_plus_populaires_pour_les_touristes_en_Sicile\"><\/span>Activit\u00e9s les plus populaires pour les touristes en Sicile<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<div data-gyg-widget=\"auto\" data-gyg-partner-id=\"2MY8JNV\" data-gyg-cmp=\"Brucoli\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":30633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[130],"tags":[],"class_list":["post-21721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-province-de-syracuse"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Brucoli est un petit village c\u00f4tier de la province de Syracuse. Si vous avez envie d&#039;admirer le ch\u00e2teau qui surplombe la mer, de respirer l&#039;air frais ou de faire quelques excursions en bateau dans la r\u00e9gion, une visite s&#039;impose. Il est juste de souligner que le ch\u00e2teau aragonais est malheureusement actuellement ferm\u00e9 pour restauration. Cependant,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dario Lo Turco\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#blogposting\",\"name\":\"Que voir \\u00e0 Brucoli \\u2013 ch\\u00e2teau, \\u00e9glise rupestre et plage\",\"headline\":\"Que voir \\u00e0 Brucoli &#8211; ch\\u00e2teau, \\u00e9glise rupestre et plage\",\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/tytryr.webp\",\"width\":1067,\"height\":682},\"datePublished\":\"2021-11-01T11:33:14+00:00\",\"dateModified\":\"2025-02-10T18:45:16+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#webpage\"},\"articleSection\":\"Province de Syracuse, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/#listItem\",\"name\":\"Province de Syracuse\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/#listItem\",\"position\":2,\"name\":\"Province de Syracuse\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#listItem\",\"name\":\"Que voir \\u00e0 Brucoli &#8211; ch\\u00e2teau, \\u00e9glise rupestre et plage\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#listItem\",\"position\":3,\"name\":\"Que voir \\u00e0 Brucoli &#8211; ch\\u00e2teau, \\u00e9glise rupestre et plage\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/#listItem\",\"name\":\"Province de Syracuse\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\",\"name\":\"Top Secret Sicily\",\"description\":\"Guide interactif de la Sicile\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"telephone\":\"+49176973190086\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-prickly-pear-50.png\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#organizationLogo\",\"width\":50,\"height\":50},\"image\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/topsecretsicily\",\"https:\\\/\\\/www.instagram.com\\\/topsecretsicily\",\"https:\\\/\\\/www.tiktok.com\\\/@topsecretsicily.com\",\"https:\\\/\\\/www.youtube.com\\\/@Topsecretsicily\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/\",\"name\":\"Dario Lo Turco\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dario Lo Turco\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#webpage\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/\",\"name\":\"Que voir \\u00e0 Brucoli \\u2013 ch\\u00e2teau, \\u00e9glise rupestre et plage\",\"description\":\"Brucoli est un petit village c\\u00f4tier de la province de Syracuse. Si vous avez envie d'admirer le ch\\u00e2teau qui surplombe la mer, de respirer l'air frais ou de faire quelques excursions en bateau dans la r\\u00e9gion, une visite s'impose. Il est juste de souligner que le ch\\u00e2teau aragonais est malheureusement actuellement ferm\\u00e9 pour restauration. Cependant,\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/tytryr.webp\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#mainImage\",\"width\":1067,\"height\":682},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-syracuse\\\/brucoli-chateau-eglise-rupestre-et-plage\\\/#mainImage\"},\"datePublished\":\"2021-11-01T11:33:14+00:00\",\"dateModified\":\"2025-02-10T18:45:16+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"name\":\"Top Secret Sicily\",\"description\":\"Guide interactif de la Sicile\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Que voir \u00e0 Brucoli \u2013 ch\u00e2teau, \u00e9glise rupestre et plage","description":"Brucoli est un petit village c\u00f4tier de la province de Syracuse. Si vous avez envie d'admirer le ch\u00e2teau qui surplombe la mer, de respirer l'air frais ou de faire quelques excursions en bateau dans la r\u00e9gion, une visite s'impose. Il est juste de souligner que le ch\u00e2teau aragonais est malheureusement actuellement ferm\u00e9 pour restauration. Cependant,","canonical_url":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#blogposting","name":"Que voir \u00e0 Brucoli \u2013 ch\u00e2teau, \u00e9glise rupestre et plage","headline":"Que voir \u00e0 Brucoli &#8211; ch\u00e2teau, \u00e9glise rupestre et plage","author":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"publisher":{"@id":"https:\/\/topsecretsicily.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/tytryr.webp","width":1067,"height":682},"datePublished":"2021-11-01T11:33:14+00:00","dateModified":"2025-02-10T18:45:16+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#webpage"},"isPartOf":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#webpage"},"articleSection":"Province de Syracuse, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/topsecretsicily.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/#listItem","name":"Province de Syracuse"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/#listItem","position":2,"name":"Province de Syracuse","item":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#listItem","name":"Que voir \u00e0 Brucoli &#8211; ch\u00e2teau, \u00e9glise rupestre et plage"},"previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#listItem","position":3,"name":"Que voir \u00e0 Brucoli &#8211; ch\u00e2teau, \u00e9glise rupestre et plage","previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/#listItem","name":"Province de Syracuse"}}]},{"@type":"Organization","@id":"https:\/\/topsecretsicily.com\/fr\/#organization","name":"Top Secret Sicily","description":"Guide interactif de la Sicile","url":"https:\/\/topsecretsicily.com\/fr\/","telephone":"+49176973190086","logo":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/03\/cropped-prickly-pear-50.png","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#organizationLogo","width":50,"height":50},"image":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/topsecretsicily","https:\/\/www.instagram.com\/topsecretsicily","https:\/\/www.tiktok.com\/@topsecretsicily.com","https:\/\/www.youtube.com\/@Topsecretsicily"]},{"@type":"Person","@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author","url":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/","name":"Dario Lo Turco","image":{"@type":"ImageObject","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dario Lo Turco"}},{"@type":"WebPage","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#webpage","url":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/","name":"Que voir \u00e0 Brucoli \u2013 ch\u00e2teau, \u00e9glise rupestre et plage","description":"Brucoli est un petit village c\u00f4tier de la province de Syracuse. Si vous avez envie d'admirer le ch\u00e2teau qui surplombe la mer, de respirer l'air frais ou de faire quelques excursions en bateau dans la r\u00e9gion, une visite s'impose. Il est juste de souligner que le ch\u00e2teau aragonais est malheureusement actuellement ferm\u00e9 pour restauration. Cependant,","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/topsecretsicily.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#breadcrumblist"},"author":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"creator":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/tytryr.webp","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#mainImage","width":1067,"height":682},"primaryImageOfPage":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/#mainImage"},"datePublished":"2021-11-01T11:33:14+00:00","dateModified":"2025-02-10T18:45:16+00:00"},{"@type":"WebSite","@id":"https:\/\/topsecretsicily.com\/fr\/#website","url":"https:\/\/topsecretsicily.com\/fr\/","name":"Top Secret Sicily","description":"Guide interactif de la Sicile","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/topsecretsicily.com\/fr\/#organization"}}]}},"aioseo_meta_data":{"post_id":"21721","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Brucoli","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2024-02-25 17:37:26","updated":"2025-02-10 18:45:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/\" title=\"Province de Syracuse\">Province de Syracuse<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQue voir \u00e0 Brucoli \u2013 ch\u00e2teau, \u00e9glise rupestre et plage\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/topsecretsicily.com\/fr\/"},{"label":"Province de Syracuse","link":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/"},{"label":"Que voir \u00e0 Brucoli &#8211; ch\u00e2teau, \u00e9glise rupestre et plage","link":"https:\/\/topsecretsicily.com\/fr\/province-de-syracuse\/brucoli-chateau-eglise-rupestre-et-plage\/"}],"modified_by":null,"_links":{"self":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/21721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/comments?post=21721"}],"version-history":[{"count":11,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/21721\/revisions"}],"predecessor-version":[{"id":49114,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/21721\/revisions\/49114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/media\/30633"}],"wp:attachment":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/media?parent=21721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/categories?post=21721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/tags?post=21721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}