{"id":26266,"date":"2021-12-28T16:37:29","date_gmt":"2021-12-28T16:37:29","guid":{"rendered":"https:\/\/topsecretsicily.com\/non-classifiee\/que-voir-a-militello-site-du-patrimoine-mondial\/"},"modified":"2025-05-06T18:15:59","modified_gmt":"2025-05-06T18:15:59","slug":"que-voir-a-militello-site-du-patrimoine-mondial","status":"publish","type":"post","link":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/","title":{"rendered":"Que voir \u00e0 Militello &#8211; Site du patrimoine mondial"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;26266&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;7&quot;,&quot;greet&quot;:&quot;\u00c9valuer l\\u0026#039;article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Que voir \u00e0 Militello - Site du patrimoine mondial&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 7px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">\u00c9valuer l&#039;article<\/span>\n    <\/div>\n    <\/div>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Introduction\" >Introduction<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Que_voir_a_Militello\" >Que voir \u00e0 Militello<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Les_eglises\" >Les \u00e9glises<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Le_chateau_de_Barresi\" >Le ch\u00e2teau de Barresi<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Produits_typiques_de_Militello\" >Produits typiques de Militello<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Activites_les_plus_populaires_pour_les_touristes_en_Sicile\" >Activit\u00e9s les plus populaires pour les touristes en Sicile<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Ou_manger_a_Militello\" >O\u00f9 manger \u00e0 Militello<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Carte_interactive_de_Militello_%E2%80%93_Points_dinteret_en_violet\" >Carte interactive de Militello &#8211; Points d&rsquo;int\u00e9r\u00eat en violet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Que_voir_dans_les_environs\" >Que voir dans les environs<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#Planifiez_vos_vacances_en_quelques_minutes\" >Planifiez vos vacances en quelques minutes<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Introduction\"><\/span>Introduction<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dans cet article, je vous parle de ce qu&rsquo;il faut voir \u00e0 Militello. Militello dans le Val di Catania a des origines byzantines et \u00e9tait alors occup\u00e9e par diff\u00e9rents peuples, comme une grande partie de la Sicile.<\/p>\n\n\n\n<p><strong>La ville est fascinante, bien qu&rsquo;elle ne soit pas du m\u00eame niveau que les autres villes baroques de Sicile<\/strong>. Bien qu&rsquo;il y ait peu de zones pi\u00e9tonnes, <strong>si vous \u00eates \u00e0 proximit\u00e9, cela vaut toujours la peine de visiter<\/strong> et de se promener pour d\u00e9couvrir les b\u00e2timents, les ruelles et les \u00e9glises, puis se reposer dans un bon restaurant en savourant la cuisine locale. Une fois arriv\u00e9, vous pouvez garer votre voiture pr\u00e8s de la villa municipale et descendre ensuite la Via Umberto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_voir_a_Militello\"><\/span>Que voir \u00e0 Militello<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-chiese\"><span class=\"ez-toc-section\" id=\"Les_eglises\"><\/span>Les \u00e9glises<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A Militello il y a vraiment de nombreuses \u00e9glises, ici vous trouverez les plus belles class\u00e9es.<\/p>\n\n\n\n<p>Sur la Piazza Municipio se trouvent l&rsquo;\u00e9glise et le <strong>monast\u00e8re de San Benedetto (XVIIe si\u00e8cle)<\/strong> , avec quelques beaux \u00e9difices baroques pour lui tenir compagnie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466-1024x768.jpg\" alt=\"\u00c9glise et monast\u00e8re de San Benedetto, Militello\" class=\"wp-image-25339\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466-1024x768.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466-768x576.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466-1536x1152.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-45-20_466.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"> \u00c9glise et monast\u00e8re de San Benedetto <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981-1024x768.jpg\" alt=\"\u00c9glise et monast\u00e8re de San Benedetto, Militello\" class=\"wp-image-25343\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981-1024x768.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981-768x576.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981-1536x1152.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-43-55_981.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"> \u00c9glise et monast\u00e8re de San Benedetto <\/figcaption><\/figure>\n\n\n\n<p>En continuant le long de la Via Umberto, vous vous retrouverez devant l&rsquo;imposante <strong>\u00e9glise de San Nicola<\/strong> , reconstruite apr\u00e8s le tremblement de terre de 1693. Attach\u00e9 \u00e0 l&rsquo;\u00e9glise se trouve le <strong>mus\u00e9e de San Nicol\u00f2, qui abrite des objets liturgiques de diff\u00e9rentes \u00e9poques<\/strong> . <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-51-24_546-768x1024.jpg\" alt=\"\u00c9glise de San Nicola, Militello\" class=\"wp-image-25335\" style=\"width:880px;height:auto\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-51-24_546-768x1024.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-51-24_546-225x300.jpg 225w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-51-24_546-1152x1536.jpg 1152w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-51-24_546.jpg 1440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Pr\u00e8s de l&rsquo;\u00e9glise il y a aussi une tr\u00e8s jolie petite place, domin\u00e9e par un <strong>petite \u00e9glise de S. Maria della Catena, de 1500. Vous devez absolument entrer dans ce lieu sacr\u00e9<\/strong>, l&rsquo;environnement int\u00e9rieur si petit et les d\u00e9corations si originales, directement taill\u00e9es dans les murs, rendent ce lieu vraiment magique.<\/p>\n\n\n\n<p>En continuant le long de la Via Umberto, \u00e0 un certain moment, la vue s&rsquo;ouvre comme de nulle part sur le<strong> sanctuaire de S. Maria della Stella<\/strong>, entour\u00e9 de vieux b\u00e2timents aux couleurs douces allant du blanc au rose.<strong> Pr\u00e8s du sanctuaire se trouve le mus\u00e9e municipal, qui abrite des vases de l&rsquo;\u00e9poque grecque et des peintures anciennes<\/strong>, ainsi qu&rsquo;une belle rue panoramique (Via Giambattista Baldanza), avec vue sur l&rsquo;\u00e9glise de San Nicola.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"38472\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/1024px-S._Maria_la_Vetere_XII-XVII_sec.jpg\" alt=\"\u00c9glise de S. Maria la Vetere, Militello\" class=\"wp-image-38472\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/1024px-S._Maria_la_Vetere_XII-XVII_sec.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/1024px-S._Maria_la_Vetere_XII-XVII_sec-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/1024px-S._Maria_la_Vetere_XII-XVII_sec-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"38474\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-24-44_264-1024x768-1.jpg\" alt=\"\u00c9glise du Purgatoire, Militello\" class=\"wp-image-38474\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-24-44_264-1024x768-1.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-24-44_264-1024x768-1-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-24-44_264-1024x768-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"38482\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-11-33_462-1024x768-1.jpg\" alt=\"\u00c9glise Piazza de Santa Maria della Stella, Militello\" class=\"wp-image-38482\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-11-33_462-1024x768-1.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-11-33_462-1024x768-1-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-11-33_462-1024x768-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"38471\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-08-14_913-1024x768-1.jpg\" alt=\"\u00c9glise de Santa Maria della Stella, Militello\" class=\"wp-image-38471\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-08-14_913-1024x768-1.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-08-14_913-1024x768-1-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2024\/05\/2021-10-01_13-08-14_913-1024x768-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Asinello a Militello\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/83mE5sBLohk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La derni\u00e8re \u00e9glise \u00e0 visiter est l&rsquo; <strong>\u00e9glise de S. Maria La Vetere<\/strong> , qui se distingue des autres, \u00e9tant immerg\u00e9e dans la nature et au milieu de cr\u00eates rocheuses. De l&rsquo;ancienne \u00e9glise il ne reste que la nef et une partie de la fa\u00e7ade, le reste a \u00e9t\u00e9 d\u00e9truit par le tremblement de terre de 1693.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-il-castello-barresi\"><span class=\"ez-toc-section\" id=\"Le_chateau_de_Barresi\"><\/span>Le ch\u00e2teau de Barresi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Militello_-_Castello_Barresi-Branciforte_sec._XIV-XVII.jpg\" alt=\"Ch\u00e2teau de Barresi-Branciforte, Militello\" class=\"wp-image-7276\" style=\"width:880px;height:auto\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Militello_-_Castello_Barresi-Branciforte_sec._XIV-XVII.jpg 721w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/12\/Militello_-_Castello_Barresi-Branciforte_sec._XIV-XVII-211x300.jpg 211w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Militello_-_Castello_Barresi-Branciforte_(sec._XIV-XVII).JPG\">Gimalgi73<\/a> , <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779-1024x768.jpg\" alt=\"Ch\u00e2teau de Baresi, Militello\" class=\"wp-image-25319\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779-1024x768.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779-768x576.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779-1536x1152.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-20-33_779.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Fontaine de la Ninfa Zizza<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089-1024x768.jpg\" alt=\"Ch\u00e2teau de Baresi, Militello\" class=\"wp-image-25323\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089-1024x768.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089-300x225.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089-768x576.jpg 768w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089-1536x1152.jpg 1536w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/11\/2021-10-01_13-21-19_089.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Et bien la visite des \u00e9glises est termin\u00e9e, il ne reste plus qu&rsquo;\u00e0 visiter <strong>le ch\u00e2teau de Barresi et la fontaine de la Ninfa Zizza<\/strong> . <strong>Aujourd&rsquo;hui, il ne reste du ch\u00e2teau qu&rsquo;une tour, une arche et une belle cour int\u00e9rieure o\u00f9 se trouve \u00e9galement une fontaine<\/strong> . La tour date du XIVe si\u00e8cle et tient son nom du baron qui la fit construire. L&rsquo;arc avec la cour int\u00e9rieure et la fontaine attenante ont plut\u00f4t \u00e9t\u00e9 construits au XVIIe \u00e0 la demande du marquis Francesco Branciforte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prodotti-tipici-di-militello\"><span class=\"ez-toc-section\" id=\"Produits_typiques_de_Militello\"><\/span>Produits typiques de Militello<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Le produit typique de Militello est un bonbon, <strong>la cassatellina di Militello<\/strong> , cr\u00e9\u00e9 dans les temps anciens par une religieuse. Cassatelline sont des paniers de p\u00e2te bris\u00e9e remplis d&rsquo;amandes, de fruits, de chocolat, de liqueur, de cannelle et de clous de girofle.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/i1.wp.com\/topsecretsicily.com\/wp-content\/uploads\/2020\/06\/1280px-Cassatelle_di_Militello.jpg?fit=800%2C533\" alt=\"Cassateline de Militello\" class=\"wp-image-3269\" style=\"width:880px;height:auto\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/06\/1280px-Cassatelle_di_Militello.jpg 1280w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/06\/1280px-Cassatelle_di_Militello-300x200.jpg 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/06\/1280px-Cassatelle_di_Militello-1024x682.jpg 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2020\/06\/1280px-Cassatelle_di_Militello-768x512.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Cassatelle_di_Militello.jpg\">Gimalgi73<\/a> , <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\">CC BY-SA 3.0<\/a> , via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p>Militello est situ\u00e9 dans la province de Catane. Ici vous trouverez <a href=\"https:\/\/topsecretsicily.com\/fr\/nourriture\/que-manger-a-catane-et-ses-environs\/\" target=\"_blank\" rel=\"noreferrer noopener\">ce qu&rsquo;il faut manger \u00e0 Catane et ses environs<\/a> .<\/p>\n\n\n\n<p>Ici, \u00e0 la place, vous trouvez le<a href=\"https:\/\/topsecretsicily.com\/fr\/nourriture\/plats-et-produits-typiques-siciliens\/\" target=\"_blank\" rel=\"noopener\" title=\"D\u00e9couvrir les plats et les produits typiques de la Sicile\"> plats typiques siciliens<\/a> en g\u00e9n\u00e9ral.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Activites_les_plus_populaires_pour_les_touristes_en_Sicile\"><\/span>Activit\u00e9s les plus populaires pour les touristes en Sicile<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div data-gyg-widget=\"auto\" data-gyg-partner-id=\"2MY8JNV\" data-gyg-cmp=\"Militello\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dove-mangiare-a-militello\"><span class=\"ez-toc-section\" id=\"Ou_manger_a_Militello\"><\/span>O\u00f9 manger \u00e0 Militello<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Deux restaurants sont recommand\u00e9s, tous deux tr\u00e8s bons. <strong>Le restaurant U &lsquo;Trappitu<\/strong> , avec des d\u00e9corations int\u00e9rieures tr\u00e8s pr\u00e9cises et caract\u00e9ristiques, telles que d&rsquo;anciennes meules en pierre, et le <strong>restaurant U pacia<\/strong> , avec un environnement int\u00e9rieur plus simple.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mappa-interattiva-di-militello-punti-d-interesse-in-viola\"><span class=\"ez-toc-section\" id=\"Carte_interactive_de_Militello_%E2%80%93_Points_dinteret_en_violet\"><\/span>Carte interactive de Militello &#8211; Points d&rsquo;int\u00e9r\u00eat en violet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Pour vous situer une fois dans la zone, cliquez sur le symbole agrandir en haut \u00e0 droite de la carte.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/u\/0\/embed?mid=1ZUwUQF3E4TwO5eo0z53SOUS4JW-uhtcp\" width=\"999\" height=\"480\"><\/iframe><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cosa-vedere-nei-dintorni\"><span class=\"ez-toc-section\" id=\"Que_voir_dans_les_environs\"><\/span>Que voir dans les environs<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Vous trouverez ici les plus beaux endroits \u00e0 visiter <a href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/\" target=\"_blank\" rel=\"noreferrer noopener\">autour de Catane<\/a> .<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"47\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-49.png\" alt=\"\" class=\"wp-image-31483\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-49.png 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-49-300x14.png 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-49-768x35.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prenotazione-volo-hotel-e-auto\"><span class=\"ez-toc-section\" id=\"Planifiez_vos_vacances_en_quelques_minutes\"><\/span>Planifiez vos vacances en quelques minutes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\ud83d\udecf\ufe0f <a href=\"https:\/\/www.booking.com\/dealspage.html?aid=8076273\">Trouver un logement sur l&rsquo;offre<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\ud83d\udeeb <a href=\"http:\/\/www.skyscanner.com\" target=\"_blank\" rel=\"noreferrer noopener\">Comparer les prix des vols<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\ud83d\ude97 <a href=\"https:\/\/www.rentalcars.com\/\">Louer une voiture \u00e0 l&rsquo;a\u00e9roport<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"47\" src=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-50.png\" alt=\"\" class=\"wp-image-31488\" srcset=\"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-50.png 1024w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-50-300x14.png 300w, https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/image-50-768x35.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":30099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[132],"tags":[],"class_list":["post-26266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-province-de-catane"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Introduction Dans cet article, je vous parle de ce qu&#039;il faut voir \u00e0 Militello. Militello dans le Val di Catania a des origines byzantines et \u00e9tait alors occup\u00e9e par diff\u00e9rents peuples, comme une grande partie de la Sicile. La ville est fascinante, bien qu&#039;elle ne soit pas du m\u00eame niveau que les autres villes baroques\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dario Lo Turco\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#blogposting\",\"name\":\"Que voir \\u00e0 Militello \\u2013 Site du patrimoine mondial\",\"headline\":\"Que voir \\u00e0 Militello &#8211; Site du patrimoine mondial\",\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/818px-S._Maria_della_Stella_XVIII_sec.webp\",\"width\":818,\"height\":1024},\"datePublished\":\"2021-12-28T16:37:29+00:00\",\"dateModified\":\"2025-05-06T18:15:59+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#webpage\"},\"articleSection\":\"Province de Catane, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/#listItem\",\"name\":\"Province de Catane\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/#listItem\",\"position\":2,\"name\":\"Province de Catane\",\"item\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#listItem\",\"name\":\"Que voir \\u00e0 Militello &#8211; Site du patrimoine mondial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#listItem\",\"position\":3,\"name\":\"Que voir \\u00e0 Militello &#8211; Site du patrimoine mondial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/#listItem\",\"name\":\"Province de Catane\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\",\"name\":\"Top Secret Sicily\",\"description\":\"Guide interactif de la Sicile\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"telephone\":\"+49176973190086\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-prickly-pear-50.png\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#organizationLogo\",\"width\":50,\"height\":50},\"image\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/topsecretsicily\",\"https:\\\/\\\/www.instagram.com\\\/topsecretsicily\",\"https:\\\/\\\/www.tiktok.com\\\/@topsecretsicily.com\",\"https:\\\/\\\/www.youtube.com\\\/@Topsecretsicily\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/\",\"name\":\"Dario Lo Turco\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dario Lo Turco\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#webpage\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/\",\"name\":\"Que voir \\u00e0 Militello \\u2013 Site du patrimoine mondial\",\"description\":\"Introduction Dans cet article, je vous parle de ce qu'il faut voir \\u00e0 Militello. Militello dans le Val di Catania a des origines byzantines et \\u00e9tait alors occup\\u00e9e par diff\\u00e9rents peuples, comme une grande partie de la Sicile. La ville est fascinante, bien qu'elle ne soit pas du m\\u00eame niveau que les autres villes baroques\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/author\\\/erf87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/818px-S._Maria_della_Stella_XVIII_sec.webp\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#mainImage\",\"width\":818,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/province-de-catane\\\/que-voir-a-militello-site-du-patrimoine-mondial\\\/#mainImage\"},\"datePublished\":\"2021-12-28T16:37:29+00:00\",\"dateModified\":\"2025-05-06T18:15:59+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/\",\"name\":\"Top Secret Sicily\",\"description\":\"Guide interactif de la Sicile\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/topsecretsicily.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Que voir \u00e0 Militello \u2013 Site du patrimoine mondial","description":"Introduction Dans cet article, je vous parle de ce qu'il faut voir \u00e0 Militello. Militello dans le Val di Catania a des origines byzantines et \u00e9tait alors occup\u00e9e par diff\u00e9rents peuples, comme une grande partie de la Sicile. La ville est fascinante, bien qu'elle ne soit pas du m\u00eame niveau que les autres villes baroques","canonical_url":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#blogposting","name":"Que voir \u00e0 Militello \u2013 Site du patrimoine mondial","headline":"Que voir \u00e0 Militello &#8211; Site du patrimoine mondial","author":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"publisher":{"@id":"https:\/\/topsecretsicily.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/818px-S._Maria_della_Stella_XVIII_sec.webp","width":818,"height":1024},"datePublished":"2021-12-28T16:37:29+00:00","dateModified":"2025-05-06T18:15:59+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#webpage"},"isPartOf":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#webpage"},"articleSection":"Province de Catane, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/topsecretsicily.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/#listItem","name":"Province de Catane"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/#listItem","position":2,"name":"Province de Catane","item":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#listItem","name":"Que voir \u00e0 Militello &#8211; Site du patrimoine mondial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#listItem","position":3,"name":"Que voir \u00e0 Militello &#8211; Site du patrimoine mondial","previousItem":{"@type":"ListItem","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/#listItem","name":"Province de Catane"}}]},{"@type":"Organization","@id":"https:\/\/topsecretsicily.com\/fr\/#organization","name":"Top Secret Sicily","description":"Guide interactif de la Sicile","url":"https:\/\/topsecretsicily.com\/fr\/","telephone":"+49176973190086","logo":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2021\/03\/cropped-prickly-pear-50.png","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#organizationLogo","width":50,"height":50},"image":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/topsecretsicily","https:\/\/www.instagram.com\/topsecretsicily","https:\/\/www.tiktok.com\/@topsecretsicily.com","https:\/\/www.youtube.com\/@Topsecretsicily"]},{"@type":"Person","@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author","url":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/","name":"Dario Lo Turco","image":{"@type":"ImageObject","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a6c943721a9cb99d40a472ead463e7044ad4c7c0d15ae5980739d7ea18a5fc90?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dario Lo Turco"}},{"@type":"WebPage","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#webpage","url":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/","name":"Que voir \u00e0 Militello \u2013 Site du patrimoine mondial","description":"Introduction Dans cet article, je vous parle de ce qu'il faut voir \u00e0 Militello. Militello dans le Val di Catania a des origines byzantines et \u00e9tait alors occup\u00e9e par diff\u00e9rents peuples, comme une grande partie de la Sicile. La ville est fascinante, bien qu'elle ne soit pas du m\u00eame niveau que les autres villes baroques","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/topsecretsicily.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#breadcrumblist"},"author":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"creator":{"@id":"https:\/\/topsecretsicily.com\/fr\/author\/erf87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/topsecretsicily.com\/wp-content\/uploads\/2023\/08\/818px-S._Maria_della_Stella_XVIII_sec.webp","@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#mainImage","width":818,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/#mainImage"},"datePublished":"2021-12-28T16:37:29+00:00","dateModified":"2025-05-06T18:15:59+00:00"},{"@type":"WebSite","@id":"https:\/\/topsecretsicily.com\/fr\/#website","url":"https:\/\/topsecretsicily.com\/fr\/","name":"Top Secret Sicily","description":"Guide interactif de la Sicile","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/topsecretsicily.com\/fr\/#organization"}}]}},"aioseo_meta_data":{"post_id":"26266","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Cosa vedere a Militello","score":37,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2024-02-20 16:15:11","updated":"2025-05-06 18:15:59","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/\" title=\"Province de Catane\">Province de Catane<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQue voir \u00e0 Militello \u2013 Site du patrimoine mondial\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/topsecretsicily.com\/fr\/"},{"label":"Province de Catane","link":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/"},{"label":"Que voir \u00e0 Militello &#8211; Site du patrimoine mondial","link":"https:\/\/topsecretsicily.com\/fr\/province-de-catane\/que-voir-a-militello-site-du-patrimoine-mondial\/"}],"modified_by":"Dario Lo Turco","_links":{"self":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/26266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/comments?post=26266"}],"version-history":[{"count":17,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/26266\/revisions"}],"predecessor-version":[{"id":50938,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/posts\/26266\/revisions\/50938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/media\/30099"}],"wp:attachment":[{"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/media?parent=26266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/categories?post=26266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/topsecretsicily.com\/fr\/wp-json\/wp\/v2\/tags?post=26266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}